{"id":11006,"date":"2025-04-10T10:31:29","date_gmt":"2025-04-10T13:31:29","guid":{"rendered":"https:\/\/datoposta.com\/destinomercedes\/?p=11006"},"modified":"2025-04-10T18:10:36","modified_gmt":"2025-04-10T21:10:36","slug":"este-fin-de-semana-convencion-de-tatuajes-en-mercedes","status":"publish","type":"post","link":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/","title":{"rendered":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES"},"content":{"rendered":"<p><strong><em>La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la <a href=\"https:\/\/datoposta.com\/destinomercedes\/mercedes-ink-2025\/\">3ra. CONVENCION DE TATUAJES MERCEDES INK 2025<\/a> que convocar\u00e1, como en las ediciones anteriores, a una multitud de entusiastas y profesionales del tatuaje, consolid\u00e1ndose como un espacio de encuentro y expresi\u00f3n art\u00edstica.<\/em><\/strong><\/p>\n<p><a href=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-10752 aligncenter\" src=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink.png\" alt=\"\" width=\"650\" height=\"643\" srcset=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink.png 650w, https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink-300x297.png 300w, https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink-607x600.png 607w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p data-sourcepos=\"1:1-1:46\"><a href=\"https:\/\/datoposta.com\/destinomercedes\/mercedes-ink-2025\/\"><strong>3ra CONVENCI\u00d3N DE TATUAJES EN MERCEDES &#8211; <\/strong><strong>\u00a1El campo en la ciudad!<\/strong><\/a><\/p>\n<p data-sourcepos=\"1:1-1:46\">Este evento ofrece al p\u00fablico la oportunidad de presenciar en vivo la realizaci\u00f3n de tatuajes y disfrutar de una variada exposici\u00f3n de artistas locales y visitantes.<\/p>\n<p data-sourcepos=\"1:1-1:46\">La convocatoria a participar del Mercedes Ink 2025 destaca la importancia de este tipo de eventos para visibilizar el tatuaje como una forma de arte y una elecci\u00f3n personal.<\/p>\n<p data-sourcepos=\"5:1-5:107\">Este a\u00f1o la convenci\u00f3n presenta grandes novedades, buscando compartir , adem\u00e1s, charlas y excursiones a lugares hist\u00f3ricos de Mercedes.<\/p>\n<p data-sourcepos=\"7:1-7:179\">La propuesta es dedicar 4 horas por d\u00eda al tatuaje (se invita a los profesionales a comenzar proyectos con anterioridad y terminarlos en la convenci\u00f3n) para as\u00ed apreciar piezas m\u00e1s grandes y conceder m\u00e1s tiempo a disfrutar de m\u00fasica en vivo y otras actividades. La convenci\u00f3n busca que los asistentes disfruten tanto del evento como de la ciudad y su gente.<\/p>\n<p data-sourcepos=\"7:1-7:179\"><a href=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/MERCEDES-INK-FLYER.png\"><img decoding=\"async\" class=\"size-full wp-image-11009 aligncenter\" src=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/MERCEDES-INK-FLYER.png\" alt=\"\" width=\"498\" height=\"650\" srcset=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/MERCEDES-INK-FLYER.png 498w, https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/MERCEDES-INK-FLYER-230x300.png 230w, https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/MERCEDES-INK-FLYER-460x600.png 460w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/a><\/p>\n<p data-sourcepos=\"13:1-13:140\">Adem\u00e1s de conferencias, talleres, paneles informativos y exposiciones, habr\u00e1 competencia de estilos, venta de accesorios e indumentaria, food trucks, patio cervecero, paseo de artesanos, skate, BMX, bandas en vivo, hip hop, Estaci\u00f3n Juego para ni\u00f1os y m\u00e1s.<\/p>\n<p data-sourcepos=\"13:1-13:140\"><a href=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/mercedes-ink.jpg\"><img decoding=\"async\" class=\"size-full wp-image-11007 aligncenter\" src=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/mercedes-ink.jpg\" alt=\"\" width=\"650\" height=\"433\" srcset=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/mercedes-ink.jpg 650w, https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/04\/mercedes-ink-300x200.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p data-sourcepos=\"13:1-13:140\">El programa para el s\u00e1bado es el siguiente:<\/p>\n<ul data-sourcepos=\"17:1-27:0\">\n<li data-sourcepos=\"17:1-17:20\">10:00 hs: Apertura<\/li>\n<li data-sourcepos=\"18:1-18:68\">14:00 hs: Chori de bienvenida (gratis para tatuadores acreditados)<\/li>\n<li data-sourcepos=\"19:1-19:45\">14:30 hs: Batalla free style, hip hop y m\u00e1s<\/li>\n<li data-sourcepos=\"20:1-20:33\">16:00 hs: Demostraci\u00f3n de skate<\/li>\n<li data-sourcepos=\"21:1-21:56\">16:30 hs: Excursi\u00f3n a la pulper\u00eda de Cacho Di Catarina<\/li>\n<li data-sourcepos=\"22:1-22:38\">17:00 hs: M\u00fasica alternativa en vivo<\/li>\n<li data-sourcepos=\"23:1-23:49\">18:00 hs: DJ Esteban Fauri (@vinilobartematico)<\/li>\n<li data-sourcepos=\"24:1-24:22\">21:00 hs: Premiaci\u00f3n<\/li>\n<li data-sourcepos=\"25:1-25:83\">22:00 hs: Vaquillona entera a pan y cuchillo (gratis para tatuadores acreditados)<\/li>\n<li data-sourcepos=\"26:1-27:0\">19:00 a 24:00 hs: Bandas de rock y cierre del evento.<\/li>\n<\/ul>\n<p data-sourcepos=\"28:1-28:65\">La convenci\u00f3n continuar\u00e1 en el tradicional bodeg\u00f3n Vinilo, tanto el s\u00e1bado como el domingo.<\/p>\n<p data-sourcepos=\"28:1-28:65\">El programa del domingo se dar\u00e1 a conocer en breve.<\/p>\n<p data-sourcepos=\"30:1-30:41\"><em><strong>La cita es en La Trocha (Av. 40 y 21, Mercedes), con entrada libre y gratuita en un evento para toda la familia.<\/strong><\/em><\/p>\n<p data-sourcepos=\"30:1-30:41\">\u00a1Los esperamos!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025 que convocar\u00e1, como en las ediciones anteriores, a una multitud de entusiastas y profesionales del tatuaje, consolid\u00e1ndose como un espacio de encuentro y expresi\u00f3n art\u00edstica. 3ra CONVENCI\u00d3N DE TATUAJES EN MERCEDES &#8211; \u00a1El [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","_jetpack_memberships_contains_paid_content":false,"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[95],"tags":[53,1927,741,1376,61,1869,1555,73,1561],"class_list":["post-11006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas","tag-agenda","tag-convencion","tag-destino-mercedes","tag-esteban-fauri","tag-la-trocha","tag-mercedes-ink","tag-tattoo","tag-tatuajes","tag-vinilo","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes<\/title>\n<meta name=\"description\" content=\"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes\" \/>\n<meta property=\"og:description\" content=\"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino Mercedes\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T13:31:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T21:10:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"destinomercedes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"destinomercedes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\"},\"author\":{\"name\":\"destinomercedes\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/695e0a82080e3c215d90b920398ff099\"},\"headline\":\"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES\",\"datePublished\":\"2025-04-10T13:31:29+00:00\",\"dateModified\":\"2025-04-10T21:10:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#organization\"},\"image\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png\",\"keywords\":[\"Agenda\",\"Convencion\",\"Destino Mercedes\",\"Esteban Fauri\",\"La Trocha\",\"Mercedes Ink\",\"Tattoo\",\"Tatuajes\",\"Vinilo\"],\"articleSection\":[\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\",\"url\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\",\"name\":\"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes\",\"isPartOf\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png\",\"datePublished\":\"2025-04-10T13:31:29+00:00\",\"dateModified\":\"2025-04-10T21:10:36+00:00\",\"description\":\"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,\",\"breadcrumb\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage\",\"url\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png\",\"contentUrl\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png\",\"width\":567,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/datoposta.com\/destinomercedes\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#website\",\"url\":\"https:\/\/datoposta.com\/destinomercedes\/\",\"name\":\"Destino Mercedes\",\"description\":\"Visita y vivi Mercedes Buenos Aires\",\"publisher\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#organization\"},\"alternateName\":\"Destino Mercedes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/datoposta.com\/destinomercedes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#organization\",\"name\":\"Destino Mercedes\",\"url\":\"https:\/\/datoposta.com\/destinomercedes\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2024\/04\/cropped-LOGO-DESTINO-MERCEDES.jpg\",\"contentUrl\":\"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2024\/04\/cropped-LOGO-DESTINO-MERCEDES.jpg\",\"width\":200,\"height\":200,\"caption\":\"Destino Mercedes\"},\"image\":{\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/695e0a82080e3c215d90b920398ff099\",\"name\":\"destinomercedes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/875299c22768defa7ce1cdf38231270fbc9a986bab7841b72ba7b92a8ed5fbf8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/875299c22768defa7ce1cdf38231270fbc9a986bab7841b72ba7b92a8ed5fbf8?s=96&d=mm&r=g\",\"caption\":\"destinomercedes\"},\"url\":\"https:\/\/datoposta.com\/destinomercedes\/author\/destinomercedes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes","description":"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes","og_description":"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,","og_url":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/","og_site_name":"Destino Mercedes","article_published_time":"2025-04-10T13:31:29+00:00","article_modified_time":"2025-04-10T21:10:36+00:00","og_image":[{"width":567,"height":431,"url":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","type":"image\/png"}],"author":"destinomercedes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"destinomercedes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#article","isPartOf":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/"},"author":{"name":"destinomercedes","@id":"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/695e0a82080e3c215d90b920398ff099"},"headline":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES","datePublished":"2025-04-10T13:31:29+00:00","dateModified":"2025-04-10T21:10:36+00:00","mainEntityOfPage":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/datoposta.com\/destinomercedes\/#organization"},"image":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage"},"thumbnailUrl":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","keywords":["Agenda","Convencion","Destino Mercedes","Esteban Fauri","La Trocha","Mercedes Ink","Tattoo","Tatuajes","Vinilo"],"articleSection":["Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/","url":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/","name":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES - Destino Mercedes","isPartOf":{"@id":"https:\/\/datoposta.com\/destinomercedes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage"},"image":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage"},"thumbnailUrl":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","datePublished":"2025-04-10T13:31:29+00:00","dateModified":"2025-04-10T21:10:36+00:00","description":"La ciudad de Mercedes vibrar\u00e1 este fin de semana con tinta y arte durante la 3ra. CONVENCION DE TATUAJES MERCEDES INK 2025,","breadcrumb":{"@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#primaryimage","url":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","contentUrl":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","width":567,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/datoposta.com\/destinomercedes\/este-fin-de-semana-convencion-de-tatuajes-en-mercedes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/datoposta.com\/destinomercedes\/"},{"@type":"ListItem","position":2,"name":"\u00a1ESTE FIN DE SEMANA! CONVENCION DE TATUAJES EN MERCEDES"}]},{"@type":"WebSite","@id":"https:\/\/datoposta.com\/destinomercedes\/#website","url":"https:\/\/datoposta.com\/destinomercedes\/","name":"Destino Mercedes","description":"Visita y vivi Mercedes Buenos Aires","publisher":{"@id":"https:\/\/datoposta.com\/destinomercedes\/#organization"},"alternateName":"Destino Mercedes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/datoposta.com\/destinomercedes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/datoposta.com\/destinomercedes\/#organization","name":"Destino Mercedes","url":"https:\/\/datoposta.com\/destinomercedes\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/logo\/image\/","url":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2024\/04\/cropped-LOGO-DESTINO-MERCEDES.jpg","contentUrl":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2024\/04\/cropped-LOGO-DESTINO-MERCEDES.jpg","width":200,"height":200,"caption":"Destino Mercedes"},"image":{"@id":"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/695e0a82080e3c215d90b920398ff099","name":"destinomercedes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/datoposta.com\/destinomercedes\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/875299c22768defa7ce1cdf38231270fbc9a986bab7841b72ba7b92a8ed5fbf8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/875299c22768defa7ce1cdf38231270fbc9a986bab7841b72ba7b92a8ed5fbf8?s=96&d=mm&r=g","caption":"destinomercedes"},"url":"https:\/\/datoposta.com\/destinomercedes\/author\/destinomercedes\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/datoposta.com\/destinomercedes\/wp-content\/uploads\/2025\/03\/mercedes-ink1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/posts\/11006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/comments?post=11006"}],"version-history":[{"count":6,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/posts\/11006\/revisions"}],"predecessor-version":[{"id":11025,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/posts\/11006\/revisions\/11025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/media\/10753"}],"wp:attachment":[{"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/media?parent=11006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/categories?post=11006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/datoposta.com\/destinomercedes\/wp-json\/wp\/v2\/tags?post=11006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}